{"id":4073,"date":"2023-09-29T13:47:11","date_gmt":"2023-09-29T13:47:11","guid":{"rendered":"https:\/\/tagderclubkultur.berlin\/fiestuki-copy\/"},"modified":"2023-09-29T13:55:58","modified_gmt":"2023-09-29T13:55:58","slug":"archivjugendkulturen","status":"publish","type":"post","link":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/","title":{"rendered":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":3997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[18],"tags":[],"class_list":["post-4073","post","type-post","status-publish","has-post-thumbnail","hentry","category-06-10"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/\" \/>\n<meta property=\"og:site_name\" content=\"TAG DER CLUBKULTUR\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T13:47:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T13:55:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3750\" \/>\n\t<meta property=\"og:image:height\" content=\"3750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"celi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"celi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/\"},\"author\":{\"name\":\"celi\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/#\\\/schema\\\/person\\\/634e4c6ef560f0a6057351106dce0b55\"},\"headline\":\"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur\",\"datePublished\":\"2023-09-29T13:47:11+00:00\",\"dateModified\":\"2023-09-29T13:55:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/\"},\"wordCount\":8,\"image\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/09\\\/TDC23_Profilbild.jpg\",\"articleSection\":[\"06.10.\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/\",\"url\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/\",\"name\":\"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/09\\\/TDC23_Profilbild.jpg\",\"datePublished\":\"2023-09-29T13:47:11+00:00\",\"dateModified\":\"2023-09-29T13:55:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/#\\\/schema\\\/person\\\/634e4c6ef560f0a6057351106dce0b55\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/09\\\/TDC23_Profilbild.jpg\",\"contentUrl\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/09\\\/TDC23_Profilbild.jpg\",\"width\":3750,\"height\":3750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/archivjugendkulturen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/\",\"name\":\"TAG DER CLUBKULTUR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/#\\\/schema\\\/person\\\/634e4c6ef560f0a6057351106dce0b55\",\"name\":\"celi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g\",\"caption\":\"celi\"},\"url\":\"https:\\\/\\\/2023.tagderclubkultur.berlin\\\/en\\\/author\\\/celi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/","og_locale":"de_DE","og_type":"article","og_title":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR","og_url":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/","og_site_name":"TAG DER CLUBKULTUR","article_published_time":"2023-09-29T13:47:11+00:00","article_modified_time":"2023-09-29T13:55:58+00:00","og_image":[{"url":"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg","width":3750,"height":3750,"type":"image\/jpeg"}],"author":"celi","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"celi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#article","isPartOf":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/"},"author":{"name":"celi","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/#\/schema\/person\/634e4c6ef560f0a6057351106dce0b55"},"headline":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur","datePublished":"2023-09-29T13:47:11+00:00","dateModified":"2023-09-29T13:55:58+00:00","mainEntityOfPage":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/"},"wordCount":8,"image":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#primaryimage"},"thumbnailUrl":"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg","articleSection":["06.10."],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/","url":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/","name":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur - TAG DER CLUBKULTUR","isPartOf":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#primaryimage"},"image":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#primaryimage"},"thumbnailUrl":"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg","datePublished":"2023-09-29T13:47:11+00:00","dateModified":"2023-09-29T13:55:58+00:00","author":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/#\/schema\/person\/634e4c6ef560f0a6057351106dce0b55"},"breadcrumb":{"@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#primaryimage","url":"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg","contentUrl":"https:\/\/2023.tagderclubkultur.berlin\/wp-content\/uploads\/sites\/23\/2023\/09\/TDC23_Profilbild.jpg","width":3750,"height":3750},{"@type":"BreadcrumbList","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/archivjugendkulturen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/2023.tagderclubkultur.berlin\/en\/"},{"@type":"ListItem","position":2,"name":"(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur"}]},{"@type":"WebSite","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/#website","url":"https:\/\/2023.tagderclubkultur.berlin\/en\/","name":"TAG DER CLUBKULTUR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/2023.tagderclubkultur.berlin\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/2023.tagderclubkultur.berlin\/en\/#\/schema\/person\/634e4c6ef560f0a6057351106dce0b55","name":"celi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca28f9555871f2759780b07b04cf1e3e7f9efeb862549e839fa624ab4cdbdb03?s=96&d=mm&r=g","caption":"celi"},"url":"https:\/\/2023.tagderclubkultur.berlin\/en\/author\/celi\/"}]}},"grid":"{\r\n  \"colCount\": 12,\r\n  \"colGutter\": 1,\r\n  \"rowGutters\": [\r\n    5,\r\n    5,\r\n    5\r\n  ],\r\n  \"frameMargin\": 1,\r\n  \"topFrameMargin\": 200,\r\n  \"bottomFrameMargin\": 5,\r\n  \"rowAttrs\": [\r\n    {\r\n      \"relid\": 23\r\n    },\r\n    {\r\n      \"relid\": 24\r\n    },\r\n    {\r\n      \"relid\": 25\r\n    },\r\n    {\r\n      \"relid\": 28\r\n    }\r\n  ],\r\n  \"bgColor\": null,\r\n  \"cont\": [\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<p class=\\\"_BIG\\\"><span>(Un)sichtbarkeiten in der Geschichte der Berliner Clubkultur<\/span><\/p>\",\r\n      \"align\": \"top\",\r\n      \"row\": 0,\r\n      \"col\": 0,\r\n      \"colspan\": 8,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 0,\r\n      \"relid\": 4,\r\n      \"absolute_position\": false\r\n    },\r\n    {\r\n      \"type\": \"img\",\r\n      \"cont\": \"\/wp-content\/uploads\/sites\/23\/2023\/09\/emergent-bass-x-archiv-der-jugendkulturen.jpg\",\r\n      \"align\": \"top\",\r\n      \"row\": 0,\r\n      \"col\": 8,\r\n      \"colspan\": 4,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 0,\r\n      \"relid\": 767,\r\n      \"attid\": 4075,\r\n      \"sizes\": {\r\n        \"full\": \"\/wp-content\/uploads\/sites\/23\/2023\/09\/emergent-bass-x-archiv-der-jugendkulturen.jpg\",\r\n        \"_512\": \"\/wp-content\/uploads\/sites\/23\/2023\/09\/emergent-bass-x-archiv-der-jugendkulturen-512x479.jpg\",\r\n        \"_265\": \"\/wp-content\/uploads\/sites\/23\/2023\/09\/emergent-bass-x-archiv-der-jugendkulturen-265x248.jpg\"\r\n      },\r\n      \"w\": 595,\r\n      \"h\": 557,\r\n      \"ar\": 0.9361344537815126,\r\n      \"alt\": \"\",\r\n      \"absolute_position\": false,\r\n      \"frameOverflow\": \"\"\r\n    },\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<p class=\\\"_Mono\\\"><span>Nachdem unser Event im Archiv der Jugendkulturen in der Woche der Clubkultur 2022 auf viel positive Resonanz gesto\u00dfen ist, m\u00f6chten wir euch auch dieses Jahr wieder zu einem Besuch des gr\u00f6\u00dften Archivs Deutschlands f\u00fcr Jugend-, Sub- und Clubkultur einladen. Ihr bekommt einen Einblick in die umfangreiche Sammlung des Archivs, in dem vielf\u00e4ltige Zeugnisse u.a. der Berliner Clubkultur bewahrt werden. Dabei m\u00f6chten wir mit euch auch \u00fcber Fragen nach (Un)Sichtbarkeiten von Schwarzer und PoC-Musikkultur und anderen vernachl\u00e4ssigten Teilen der Berliner Clubkulturgeschichte sprechen und einen kritischen Blick auf die clubkulturelle Geschichtsschreibung werfen.<\/span><\/p><p class=\\\"_Mono\\\">\u00a0<\/p><p class=\\\"_Mono\\\"><span>Line-Up\/ Programm:\u00a0<\/span><span><br \/>17:15 Start der Tour durch das Archiv <br \/><a href=\\\"http:\/\/HTTPS:\/\/WWW.INSTAGRAM.COM\/P\/CXXYGV4MS8M\/\\\">Instagram<\/a> <br \/><a href=\\\"http:\/\/HTTPS:\/\/WWW.FACEBOOK.COM\/EVENTS\/352578790439204\\\">Facebook<\/a><\/span><\/p><p class=\\\"_Mono\\\">\u00a0<\/p>\",\r\n      \"align\": \"top\",\r\n      \"row\": 1,\r\n      \"col\": 0,\r\n      \"colspan\": 5,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 0,\r\n      \"relid\": 407,\r\n      \"absolute_position\": false\r\n    },\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<p class=\\\"_Mono\\\">DATUM<\/p><p class=\\\"_Mono\\\">06.10.<\/p><p>\u00a0<\/p><p class=\\\"_Mono\\\">ZEIT<\/p><p class=\\\"_Mono\\\">17 - 19 Uhr<\/p><p>\u00a0<\/p><p class=\\\"_Mono\\\">LOCATION<br \/><span>Archiv der Jugendkulturen e.V.<br \/>Fidicinstr. 3, Haus B<br \/>10965 Berlin\u00a0<br \/><\/span><\/p><p>\u00a0<\/p><p class=\\\"_Mono\\\">ART DER VERANSTALTUNG<br \/><span>F\u00fchrung und Diskussion<\/span><br \/><br \/>TICKETPREIS<br \/><span>0 \u20ac<\/span><\/p>\",\r\n      \"align\": \"top\",\r\n      \"row\": 1,\r\n      \"col\": 6,\r\n      \"colspan\": 4,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 1,\r\n      \"relid\": 6,\r\n      \"absolute_position\": false\r\n    },\r\n    {\r\n      \"type\": \"hr\",\r\n      \"cont\": \"\",\r\n      \"align\": \"top\",\r\n      \"row\": 2,\r\n      \"col\": 0,\r\n      \"colspan\": 12,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 0,\r\n      \"relid\": 8,\r\n      \"frameOverflow\": \"\",\r\n      \"absolute_position\": false\r\n    },\r\n    {\r\n      \"type\": \"hr\",\r\n      \"cont\": \"\",\r\n      \"align\": \"top\",\r\n      \"row\": 3,\r\n      \"col\": 0,\r\n      \"colspan\": 12,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 0,\r\n      \"relid\": 7,\r\n      \"frameOverflow\": \"\",\r\n      \"absolute_position\": false\r\n    }\r\n  ]\r\n}","phonegrid":"","_links":{"self":[{"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/posts\/4073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/comments?post=4073"}],"version-history":[{"count":0,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/posts\/4073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/media\/3997"}],"wp:attachment":[{"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/media?parent=4073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/categories?post=4073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2023.tagderclubkultur.berlin\/en\/wp-json\/wp\/v2\/tags?post=4073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}